{"id":11573,"date":"2025-02-10T16:42:32","date_gmt":"2025-02-10T08:42:32","guid":{"rendered":"http:\/\/st.fogcm.com\/?page_id=11573"},"modified":"2025-10-10T15:34:22","modified_gmt":"2025-10-10T07:34:22","slug":"implement-wheels%e7%b3%bb%e5%88%97%e8%a1%a8","status":"publish","type":"page","link":"https:\/\/www.uniglorytire.com\/fr\/lawn-garden-turf\/implement-wheels%e7%b3%bb%e5%88%97%e8%a1%a8\/","title":{"rendered":"IMPLEMENT WHEELS"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"11573\" class=\"elementor elementor-11573\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ebbdd6d elementor-section-height-min-height elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5ebbdd6d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-183178bc\" data-id=\"183178bc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-477af977 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"477af977\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-665013d\" data-id=\"665013d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10077aac elementor-widget elementor-widget-elementskit-heading\" data-id=\"10077aac\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\">IMPLEMENT WHEELS<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-67aa3e08 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67aa3e08\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-38b17166\" data-id=\"38b17166\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d378f02 elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-elementskit-button\" data-id=\"2d378f02\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tContact Us\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f056ec5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f056ec5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7686c5f2\" data-id=\"7686c5f2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-686c04a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"686c04a0\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-67f00e39\" data-id=\"67f00e39\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6dc2faa6 elementor-widget elementor-widget-heading\" data-id=\"6dc2faa6\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">IMPLEMENT WHEELS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ab1ed41 elementor-widget elementor-widget-text-editor\" data-id=\"4ab1ed41\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>&#8220;Feel where traction goes hand in hand with comfort.&#8221;<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2834daeb elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2834daeb\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">A wide range of sizes - Meet the needs of a wide variety of the agricultural and municipal machines.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Unmatched Load Capacity \u2013 Engineered for maximum strength, outperforming competitors.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ultra-Durable Discs \u2013 Precisely manufactured up to 20mm thick for failure-free performance.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Custom Colors \u2013 Full RAL palette and OEM-specific colors available on request.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6f63eb48\" data-id=\"6f63eb48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f0eb62f elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"1f0eb62f\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d&#039;images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 1\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1f0eb62f\" data-elementor-lightbox-title=\"IMPLEMENT\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTE1NzYsInVybCI6Imh0dHBzOlwvXC93d3cudW5pZ2xvcnl0aXJlLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDJcL0lNUExFTUVOVC5wbmciLCJzbGlkZXNob3ciOiIxZjBlYjYyZiJ9\" href=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2025\/02\/IMPLEMENT.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2025\/02\/IMPLEMENT-300x284.png\" alt=\"IMPLEMENT\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-41930575 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"41930575\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-11390e3f\" data-id=\"11390e3f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46b889ce elementor-widget elementor-widget-elementskit-heading\" data-id=\"46b889ce\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\">\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Tires are the essential point of contact between your car and the road. We work to ensure that your tires will always offer excellent braking, maximum safety, and pure driving pleasure.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-37904f0a\" data-id=\"37904f0a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e3a0cf1 elementor-align-right elementor-align--mobilecenter elementor-widget elementor-widget-elementskit-button\" data-id=\"1e3a0cf1\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tContact\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-176dee43 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"176dee43\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a5e2640\" data-id=\"3a5e2640\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5130d7ea elementor-widget elementor-widget-heading\" data-id=\"5130d7ea\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Technical detalis<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6e978bd4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e978bd4\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-13415cca\" data-id=\"13415cca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21ca6a91 elementor-widget elementor-widget-image\" data-id=\"21ca6a91\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/11\/1701071573979-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-5884\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/11\/1701071573979-150x150.png 150w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/11\/1701071573979-300x300.png 300w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/11\/1701071573979.png 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-59dfae0a\" data-id=\"59dfae0a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b2127cf elementor-widget elementor-widget-text-editor\" data-id=\"7b2127cf\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>UNIGLORY R&amp;D teams have dedicated over a decade to developing high-strength wheel rims for superior durability in agricultural and industrial applications.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-765a39b8 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"765a39b8\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">High-Strength Steel Construction \uff1a Precision-engineered rims using premium steel alloys enhance load-bearing capacity and impact resistance.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Advanced Welding & Forming Technology \uff1a Automated manufacturing ensures structural integrity, reducing weak points and increasing lifespan.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Optimized Disc Design \uff1a Thickened disc structures and reinforced bead seats provide exceptional strength in high-stress environments.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Enhanced Corrosion Resistance \uff1a A multi-layer powder coating process offers long-lasting protection against rust, chemicals, and harsh weather.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Precision Balancing \uff1a Engineered for uniform weight distribution, minimizing vibration and improving operational stability.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e59c9f6 elementor-widget elementor-widget-text-editor\" data-id=\"5e59c9f6\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The results are the outstanding service life of agriculture &amp; industrial wheels, increased by more than 30%.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54b1ba02 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"54b1ba02\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50a38179\" data-id=\"50a38179\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5cb7d900 elementor-widget elementor-widget-elementskit-tablepress\" data-id=\"5cb7d900\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-tablepress.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elemenetskit-tablepress ekit-wid-con\" id=\"ekit_tablepress_5cb7d900\">\n<table id=\"tablepress-404\" class=\"tablepress tablepress-id-404\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\"><span style=\"color:#FFFFFF;\"><strong>Wheel Dia.\uff08in\uff09<\/strong><\/span><\/th><th class=\"column-2\"><span style=\"color:#FFFFFF;\"><strong>Rim profile<\/strong><\/span><\/th><th class=\"column-3\"><span style=\"color:#FFFFFF;\"><strong>Tyre sizes<\/strong><\/span><\/th><th class=\"column-4\"><span style=\"color:#FFFFFF;\"><strong>Maximum load capacity (kg)  at 40 km\/h<\/strong><\/span><\/th><th class=\"column-5\"><span style=\"color:#FFFFFF;\"><strong>Maximum speed ( km\/h)<\/strong><\/span><\/th><th class=\"column-6\"><span style=\"color:#FFFFFF;\"><strong>Maximum offset ranges (mm)<\/strong><\/span><\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">12\u201d<\/td><td class=\"column-2\">4.25x12<\/td><td class=\"column-3\">7.00-12<\/td><td class=\"column-4\">950<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+38\/-44(wentylem <br \/>\ndo maszyny<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">12\u201d<\/td><td class=\"column-2\">5JAx12<\/td><td class=\"column-3\">6.5\/80-12<\/td><td class=\"column-4\">950<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+47\/-53(wentylem <br \/>\ndo maszyny)<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">12\u201d<\/td><td class=\"column-2\">7.00x12<\/td><td class=\"column-3\">10.0\/80-12<\/td><td class=\"column-4\">950<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+64\/-70<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">15\u201d<\/td><td class=\"column-2\">9.00x15<\/td><td class=\"column-3\">10.0\/75-15.3; <br \/>\n11.5\/80-15.3<\/td><td class=\"column-4\">1750<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+99\/-105<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">15,3\u201d<\/td><td class=\"column-2\">9.00x15.3<\/td><td class=\"column-3\">10.0\/75-15.3; 10.0\/80-12; 11.5\/80-15.3; <br \/>\n12.5\/80-15.3; 260\/70-15.3<\/td><td class=\"column-4\">3000<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+105\/-113<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">15.5\u201d<\/td><td class=\"column-2\">13.00x15.5<\/td><td class=\"column-3\">400\/60-15.5<\/td><td class=\"column-4\">3500<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+152\/-160<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">15.5\u201d<\/td><td class=\"column-2\">13.00x15.5H2<\/td><td class=\"column-3\">400\/60-15.5<\/td><td class=\"column-4\">3300<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+152\/-160<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">16\u201d<\/td><td class=\"column-2\">4.50Ex16<\/td><td class=\"column-3\">6.00-16<\/td><td class=\"column-4\">870<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+53\/-59(wentylem <br \/>\ndo maszyny)<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">16\u201d<\/td><td class=\"column-2\">5.50Fx16<\/td><td class=\"column-3\">7.50-16<\/td><td class=\"column-4\">870<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+56\/-62<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">16\u201d<\/td><td class=\"column-2\">9.00x16<\/td><td class=\"column-3\">10.5\/65-16<\/td><td class=\"column-4\">2350<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+104\/-110<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">16\u201d<\/td><td class=\"column-2\">11x16<\/td><td class=\"column-3\">13.0\/55-16; 13.0\/75-16; 14.0\/65-16<\/td><td class=\"column-4\">3000<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+127\/-133<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">17\u201d<\/td><td class=\"column-2\">13.00x17<\/td><td class=\"column-3\">15.0\/55-17; 420\/55-17<\/td><td class=\"column-4\">3350<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+144\/-154<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">17\u201d<\/td><td class=\"column-2\">16.00x17<\/td><td class=\"column-3\">19.0\/45-17; 500\/50-17; 500\/65-17<\/td><td class=\"column-4\">4750<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+182\/-192<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">17\u201d<\/td><td class=\"column-2\">16.00x17<\/td><td class=\"column-3\">19.0\/45-17; 500\/50-17; 500\/65-17<\/td><td class=\"column-4\">4750<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+182\/-192<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">18\u201d<\/td><td class=\"column-2\">5.50Fx18<\/td><td class=\"column-3\">7.50-18<\/td><td class=\"column-4\">1250<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+60\/-68 (with <br \/>\nvalve guard on the <br \/>\nmachine\u2019s side)<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">18\u201d<\/td><td class=\"column-2\">9.00x18<\/td><td class=\"column-3\">10.5\/80-18; 12.0\/75-18; 12.5\/80-18<\/td><td class=\"column-4\">3500<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+75\/-85<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">18\u201d<\/td><td class=\"column-2\">W9x18<\/td><td class=\"column-3\">10.5\/80-18; 12.0\/75-18; 12.5\/80-18<\/td><td class=\"column-4\">3075<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+43\/-53<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">18\u201d<\/td><td class=\"column-2\">11x18<\/td><td class=\"column-3\">12.0-18; 12.5\/80-18; 13.0\/65-18; <br \/>\n14.5\/80-18<\/td><td class=\"column-4\">3800<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+98\/-108<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">18\u201d<\/td><td class=\"column-2\">13x18<\/td><td class=\"column-3\">400\/60R18; 15.0\/70-18<\/td><td class=\"column-4\">3800<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+124\/-134<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">20\u201d<\/td><td class=\"column-2\">13x20<\/td><td class=\"column-3\">16.0\/70-20<\/td><td class=\"column-4\">3500<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+147\/-157<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">22.5\u201d<\/td><td class=\"column-2\">16.00x22.5<\/td><td class=\"column-3\">500\/45 R22.5;500\/50R22.5;<br \/>\n500\/60-22.5;500\/60 R22.5;<br \/>\n550\/45-22.5;550\/60-22.5;<br \/>\n560\/45R22.5;560\/60R22.5<\/td><td class=\"column-4\">6500<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+176\/-190 <br \/>\n(with valve guard <br \/>\non the machine\u2019s side)<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">24\u201d<\/td><td class=\"column-2\">W12<\/td><td class=\"column-3\">15.5\/80-24<\/td><td class=\"column-4\">4700<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+143\/-153<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">24\u201d<\/td><td class=\"column-2\">W13<\/td><td class=\"column-3\">15.5\/80-24; 16.5\/85-24; 400\/80-24<\/td><td class=\"column-4\">4700<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+155.5\/-165.5<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">24\u201d<\/td><td class=\"column-2\">W14L<\/td><td class=\"column-3\">15.5\/80-24<\/td><td class=\"column-4\">4700<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+160\/-170<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">24\u201d<\/td><td class=\"column-2\">W15L<\/td><td class=\"column-3\">17.5L-24<\/td><td class=\"column-4\">4700<\/td><td class=\"column-5\">40<\/td><td class=\"column-6\">+172\/-182<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-404 from cache --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f41cd07 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f41cd07\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0dcf231\" data-id=\"0dcf231\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed0a722 elementor-widget elementor-widget-heading\" data-id=\"ed0a722\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Downloads<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9a0d12f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9a0d12f\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-dc38e95\" data-id=\"dc38e95\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f1c679 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8f1c679\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">TRACTOR FIXED WHEELS\u200b<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-be5cfbd\" data-id=\"be5cfbd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d80c89d elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d80c89d\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">IMPLEMENT WHEELS<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-646e440\" data-id=\"646e440\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d65d6cd elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d65d6cd\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">WHEELS FOR COMBINE HARVESTERS<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-1897d95\" data-id=\"1897d95\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a43006d elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"a43006d\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">TRAILER AND FLOTATION WHEELS<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-2db5032\" data-id=\"2db5032\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90eab83 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"90eab83\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">ROW CROP WHEELS<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7ff22f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ff22f8\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-0d031fc\" data-id=\"0d031fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9cb519 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b9cb519\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">ROW CROP WHEELS<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-00b19f6\" data-id=\"00b19f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc52e28 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"fc52e28\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">WHEELS FOR FORESTRY MACHINES<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-58330f4\" data-id=\"58330f4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10011b6 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"10011b6\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">CONSTRUCTION AND UTILTY WHEELS<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-5b99b42\" data-id=\"5b99b42\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aebdf9c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"aebdf9c\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">MINING WHEELS<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-f4dbaa0\" data-id=\"f4dbaa0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>IMPLEMENT WHEELS Contact Us IMPLEMENT WHEELS &#8220;Feel where traction goes hand in hand with comfort.&#8221; A wide range of sizes &#8211; Meet the needs of a wide variety of the agricultural and municipal machines. Unmatched Load Capacity \u2013 Engineered for maximum strength, outperforming competitors. Ultra-Durable Discs \u2013 Precisely manufactured up to 20mm thick for failure-free [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3256,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-11573","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.uniglorytire.com\/fr\/wp-json\/wp\/v2\/pages\/11573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uniglorytire.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.uniglorytire.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.uniglorytire.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uniglorytire.com\/fr\/wp-json\/wp\/v2\/comments?post=11573"}],"version-history":[{"count":4,"href":"https:\/\/www.uniglorytire.com\/fr\/wp-json\/wp\/v2\/pages\/11573\/revisions"}],"predecessor-version":[{"id":15588,"href":"https:\/\/www.uniglorytire.com\/fr\/wp-json\/wp\/v2\/pages\/11573\/revisions\/15588"}],"up":[{"embeddable":true,"href":"https:\/\/www.uniglorytire.com\/fr\/wp-json\/wp\/v2\/pages\/3256"}],"wp:attachment":[{"href":"https:\/\/www.uniglorytire.com\/fr\/wp-json\/wp\/v2\/media?parent=11573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}