{"id":11525,"date":"2025-02-10T15:15:06","date_gmt":"2025-02-10T07:15:06","guid":{"rendered":"http:\/\/st.fogcm.com\/?page_id=11525"},"modified":"2025-10-10T16:09:04","modified_gmt":"2025-10-10T08:09:04","slug":"tractor-fixed-wheels%e7%b3%bb%e5%88%97%e8%a1%a8","status":"publish","type":"page","link":"https:\/\/www.uniglorytire.com\/id\/lawn-garden-turf\/tractor-fixed-wheels%e7%b3%bb%e5%88%97%e8%a1%a8\/","title":{"rendered":"TRACTOR FIXED WHEELS"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"11525\" class=\"elementor elementor-11525\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ebbdd6d elementor-section-height-min-height elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5ebbdd6d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-183178bc\" data-id=\"183178bc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-477af977 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"477af977\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-665013d\" data-id=\"665013d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10077aac elementor-widget elementor-widget-elementskit-heading\" data-id=\"10077aac\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\">TRACTOR FIXED WHEELS<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-67aa3e08 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67aa3e08\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-38b17166\" data-id=\"38b17166\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d378f02 elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-elementskit-button\" data-id=\"2d378f02\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tContact Us\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f056ec5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f056ec5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7686c5f2\" data-id=\"7686c5f2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-686c04a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"686c04a0\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-67f00e39\" data-id=\"67f00e39\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6dc2faa6 elementor-widget elementor-widget-heading\" data-id=\"6dc2faa6\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TRACTOR FIXED WHEELS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ab1ed41 elementor-widget elementor-widget-text-editor\" data-id=\"4ab1ed41\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>&#8220;Feel where traction goes hand in hand with comfort.&#8221;<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2834daeb elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2834daeb\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Extreme Durability \u2013 Discs up to 20mm thick for tough conditions.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">High Load Capacity \u2013 Steel rims up to 9mm thick for maximum strength.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Precision & Aesthetics \u2013 Advanced automation ensures perfect consistency.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Superior Corrosion Protection \u2013 Multistage powder coating for unmatched resistance.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6f63eb48\" data-id=\"6f63eb48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f0eb62f elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"1f0eb62f\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Karusel Gambar\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 1\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1f0eb62f\" data-elementor-lightbox-title=\"PRONAR-TRACTOR\u56fe\u7247\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA3NjQsInVybCI6Imh0dHBzOlwvXC93d3cudW5pZ2xvcnl0aXJlLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDFcL1BST05BUi1UUkFDVE9SXHU1NmZlXHU3MjQ3LmpwZyIsInNsaWRlc2hvdyI6IjFmMGViNjJmIn0%3D\" href=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2025\/01\/PRONAR-TRACTOR\u56fe\u7247.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2025\/01\/PRONAR-TRACTOR\u56fe\u7247.jpg\" alt=\"PRONAR-TRACTOR\u56fe\u7247\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-41930575 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"41930575\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-11390e3f\" data-id=\"11390e3f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46b889ce elementor-widget elementor-widget-elementskit-heading\" data-id=\"46b889ce\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\">\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Tires are the essential point of contact between your car and the road. We work to ensure that your tires will always offer excellent braking, maximum safety, and pure driving pleasure.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-37904f0a\" data-id=\"37904f0a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e3a0cf1 elementor-align-right elementor-align--mobilecenter elementor-widget elementor-widget-elementskit-button\" data-id=\"1e3a0cf1\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tKontak\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-176dee43 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"176dee43\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a5e2640\" data-id=\"3a5e2640\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5130d7ea elementor-widget elementor-widget-heading\" data-id=\"5130d7ea\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Technical detalis<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6e978bd4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e978bd4\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-13415cca\" data-id=\"13415cca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21ca6a91 elementor-widget elementor-widget-image\" data-id=\"21ca6a91\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/11\/1701071573979-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-5884\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/11\/1701071573979-150x150.png 150w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/11\/1701071573979-300x300.png 300w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/11\/1701071573979.png 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-59dfae0a\" data-id=\"59dfae0a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b2127cf elementor-widget elementor-widget-text-editor\" data-id=\"7b2127cf\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>UNIGLORY R&amp;D teams have dedicated over a decade to developing high-strength wheel rims for superior durability in agricultural and industrial applications.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-765a39b8 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"765a39b8\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">High-Strength Steel Construction \uff1a Precision-engineered rims using premium steel alloys enhance load-bearing capacity and impact resistance.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Advanced Welding & Forming Technology \uff1a Automated manufacturing ensures structural integrity, reducing weak points and increasing lifespan.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Optimized Disc Design \uff1a Thickened disc structures and reinforced bead seats provide exceptional strength in high-stress environments.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Enhanced Corrosion Resistance \uff1a A multi-layer powder coating process offers long-lasting protection against rust, chemicals, and harsh weather.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Precision Balancing \uff1a Engineered for uniform weight distribution, minimizing vibration and improving operational stability.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e59c9f6 elementor-widget elementor-widget-text-editor\" data-id=\"5e59c9f6\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Results<br \/>The results are the outstanding service life of industrial tire, increased by more than\u00a0<strong><span style=\"color: #ffcc00;\">28%<\/span>.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54b1ba02 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"54b1ba02\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50a38179\" data-id=\"50a38179\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5cb7d900 elementor-widget elementor-widget-elementskit-tablepress\" data-id=\"5cb7d900\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-tablepress.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elemenetskit-tablepress ekit-wid-con\" id=\"ekit_tablepress_5cb7d900\">\n<table id=\"tablepress-408\" class=\"tablepress tablepress-id-408\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\"><span style=\"color:#FFFFFF;\"><strong>Wheel Dia.\uff08in\uff09<\/strong><\/span><\/th><th class=\"column-2\"><span style=\"color:#FFFFFF;\"><strong>Rim profile<\/strong><\/span><\/th><th class=\"column-3\"><span style=\"color:#FFFFFF;\"><strong>Tyre sizes<\/strong><\/span><\/th><th class=\"column-4\"><span style=\"color:#FFFFFF;\"><strong><span style=\"color:#FFFFFF;\"><strong>Load capacity (kg) at 40 km\/h<\/strong><\/span><span style=\"color:#FFFFFF;\"><strong><sup>1<\/sup><\/strong><\/span><span style=\"color:#FFFFFF;\"><strong>)<\/strong><\/span><\/strong><\/span><\/th><th class=\"column-5\"><span style=\"color:#FFFFFF;\"><strong>Maximum offset ranges (mm)<\/strong><\/span><\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">12\u201d<\/td><td class=\"column-2\">4.25<\/td><td class=\"column-3\">7-12.00<\/td><td class=\"column-4\">950<\/td><td class=\"column-5\">+38\/-44\u00b2\u207e<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">12\u201d<\/td><td class=\"column-2\">5JA<\/td><td class=\"column-3\">6.5\/80-12<\/td><td class=\"column-4\">950<\/td><td class=\"column-5\">+47\/-53\u00b2\u207e<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">12\u201d<\/td><td class=\"column-2\">7<\/td><td class=\"column-3\">10\/80-12<\/td><td class=\"column-4\">950<\/td><td class=\"column-5\">+64\/-70<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">12\u201d<\/td><td class=\"column-2\">1050<\/td><td class=\"column-3\">24x12.00-12<\/td><td class=\"column-4\">1000<\/td><td class=\"column-5\">+108\/-114<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">15\u201d<\/td><td class=\"column-2\">7,00<\/td><td class=\"column-3\">6.50\/80-15<\/td><td class=\"column-4\">1100<\/td><td class=\"column-5\">+90\/-98\u00b2\u207e<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">15\u201d<\/td><td class=\"column-2\">10LB<\/td><td class=\"column-3\">320\/55-15; 320\/60-15<\/td><td class=\"column-4\">2000<\/td><td class=\"column-5\">+15\/-81<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">15.3\u201d<\/td><td class=\"column-2\">9<\/td><td class=\"column-3\">10.0\/75-15.3; 11.5\/80-15.3<\/td><td class=\"column-4\">3000<\/td><td class=\"column-5\">+105\/-113<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">16\u201d<\/td><td class=\"column-2\">4,00E<\/td><td class=\"column-3\">5.50-16<\/td><td class=\"column-4\">600<\/td><td class=\"column-5\">+45\/-51<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">16\u201d<\/td><td class=\"column-2\">4,50E<\/td><td class=\"column-3\">6.00-16<\/td><td class=\"column-4\">870<\/td><td class=\"column-5\">+53\/-59\u00b2\u207e<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">16\u201d<\/td><td class=\"column-2\">5,00F<\/td><td class=\"column-3\">7.50-16; 180\/95R16<\/td><td class=\"column-4\">870<\/td><td class=\"column-5\">+53\/-59<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">16\u201d<\/td><td class=\"column-2\">5,50F<\/td><td class=\"column-3\">6,50-16; 7.50-16<\/td><td class=\"column-4\">870<\/td><td class=\"column-5\">+56\/-62<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">16\u201d<\/td><td class=\"column-2\">6,00L<\/td><td class=\"column-3\">7-16; 8-16<\/td><td class=\"column-4\">1300<\/td><td class=\"column-5\">+68\/-74\u00b2\u207e<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">16\u201d<\/td><td class=\"column-2\">W6<\/td><td class=\"column-3\">200\/70R16<\/td><td class=\"column-4\">2000<\/td><td class=\"column-5\">+114\/-126<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">16\u201d<\/td><td class=\"column-2\">W7<\/td><td class=\"column-3\">200\/70R16; 220\/70R16<\/td><td class=\"column-4\">2400<\/td><td class=\"column-5\">+126\/-138<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">16\u201d<\/td><td class=\"column-2\">W8<\/td><td class=\"column-3\">240\/70R16; 260\/70R16; 275\/65R16; <br \/>\n320\/65R16<\/td><td class=\"column-4\">2400<\/td><td class=\"column-5\">+138\/-150<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">16\u201d<\/td><td class=\"column-2\">9,00<\/td><td class=\"column-3\">10.5\/65-16<\/td><td class=\"column-4\">2350<\/td><td class=\"column-5\">+104\/-110<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">16\u201d<\/td><td class=\"column-2\">W10<\/td><td class=\"column-3\">11.00-16<\/td><td class=\"column-4\">2800<\/td><td class=\"column-5\">+163\/-175<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">16\u201d<\/td><td class=\"column-2\">W12x16<\/td><td class=\"column-3\">13.6R16<\/td><td class=\"column-4\">3200<\/td><td class=\"column-5\">+188\/-200<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">18\u201d<\/td><td class=\"column-2\">4,50E<\/td><td class=\"column-3\">6.00-18<\/td><td class=\"column-4\">670<\/td><td class=\"column-5\">+52\/-60\u00b2\u207e<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">18\u201d<\/td><td class=\"column-2\">5,50F<\/td><td class=\"column-3\">7.50-18<\/td><td class=\"column-4\">1250<\/td><td class=\"column-5\">+60\/-68\u00b2\u207e<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">18\u201d<\/td><td class=\"column-2\">9,00<\/td><td class=\"column-3\">10.5\/80-18; 12.5\/80-18; 275\/80R18<\/td><td class=\"column-4\">3500<\/td><td class=\"column-5\">+75\/-85<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">18\u201d<\/td><td class=\"column-2\">11,00<\/td><td class=\"column-3\">340\/65R18<\/td><td class=\"column-4\">3800<\/td><td class=\"column-5\">+98\/-108<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">19.5\u201d<\/td><td class=\"column-2\">11.75<\/td><td class=\"column-3\">380\/70D19.5; 15-19.5<\/td><td class=\"column-4\">3500<\/td><td class=\"column-5\">+111\/-123<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">19.5\u201d<\/td><td class=\"column-2\">12.25<\/td><td class=\"column-3\">15-19.5<\/td><td class=\"column-4\">3500<\/td><td class=\"column-5\">+117.5\/-129.5<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">20\u201d<\/td><td class=\"column-2\">5,5F<\/td><td class=\"column-3\">6.50-20; 7.50-20<\/td><td class=\"column-4\">880<\/td><td class=\"column-5\">+50\/-58<\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">20\u201d<\/td><td class=\"column-2\">W7<\/td><td class=\"column-3\">8.3-20; 9.5-20; 210\/95R20<\/td><td class=\"column-4\">3300<\/td><td class=\"column-5\">+113\/-121<\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\">20\u201d<\/td><td class=\"column-2\">W8<\/td><td class=\"column-3\">280\/70R20; 260\/70R20; 250\/85R20<\/td><td class=\"column-4\">4000<\/td><td class=\"column-5\">+125\/-133<\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\">20\u201d<\/td><td class=\"column-2\">W9<\/td><td class=\"column-3\">10,5R20; 280\/70R20; 280\/80R20; <br \/>\n300\/70R20<\/td><td class=\"column-4\">3700<\/td><td class=\"column-5\">+132\/-140<\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\">20\u201d<\/td><td class=\"column-2\">W10<\/td><td class=\"column-3\">11.2-24; 12.5R20; 320\/70R20; <br \/>\n340\/80R20; 420\/65R20<\/td><td class=\"column-4\">3600<\/td><td class=\"column-5\">+144\/-152<\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\">20\u201d<\/td><td class=\"column-2\">W11<\/td><td class=\"column-3\">340\/80R20; 375\/75R20; 12.4-24; <br \/>\n340\/65R20; 360\/70R20; 320\/85R20<\/td><td class=\"column-4\">3600<\/td><td class=\"column-5\">+156.5\/-164.5<\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\">20\u201d<\/td><td class=\"column-2\">W12<\/td><td class=\"column-3\">14.5R20; 380\/75R20; 380\/70R20<\/td><td class=\"column-4\">4000<\/td><td class=\"column-5\">+169\/-177<\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\">20\u201d<\/td><td class=\"column-2\">W13<\/td><td class=\"column-3\">380\/70R20; 14.9-24; 420\/65R20<\/td><td class=\"column-4\">3800<\/td><td class=\"column-5\">+181\/-189<\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td class=\"column-1\">20\u201d<\/td><td class=\"column-2\">W14\/W14L<\/td><td class=\"column-3\">440\/65R20<\/td><td class=\"column-4\">3500<\/td><td class=\"column-5\">+185.5\/-193.5<\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\">20\u201d<\/td><td class=\"column-2\">W16L<\/td><td class=\"column-3\">500\/45-20; 500\/50-20<\/td><td class=\"column-4\">4500<\/td><td class=\"column-5\">+211\/-219<\/td>\n<\/tr>\n<tr class=\"row-36\">\n\t<td class=\"column-1\">24\u201d<\/td><td class=\"column-2\">W7<\/td><td class=\"column-3\">8.3-24<\/td><td class=\"column-4\">3300<\/td><td class=\"column-5\">+84.5\/-94.5<\/td>\n<\/tr>\n<tr class=\"row-37\">\n\t<td class=\"column-1\">24\u201d<\/td><td class=\"column-2\">W8<\/td><td class=\"column-3\">9.5-24; 250\/85R24<\/td><td class=\"column-4\">3300<\/td><td class=\"column-5\">+97\/-107<\/td>\n<\/tr>\n<tr class=\"row-38\">\n\t<td class=\"column-1\">24\u201d<\/td><td class=\"column-2\">W9<\/td><td class=\"column-3\">11.2R24; 12.4-24<\/td><td class=\"column-4\">3300<\/td><td class=\"column-5\">+104.5\/-114.5<\/td>\n<\/tr>\n<tr class=\"row-39\">\n\t<td class=\"column-1\">24\u201d<\/td><td class=\"column-2\">W10<\/td><td class=\"column-3\">11.2R24; 320\/70R24<\/td><td class=\"column-4\">4700<\/td><td class=\"column-5\">+117.5\/-127.5<\/td>\n<\/tr>\n<tr class=\"row-40\">\n\t<td class=\"column-1\">24\u201d<\/td><td class=\"column-2\">W11<\/td><td class=\"column-3\">12.4R24; 14.9-24; 300\/80R24; <br \/>\n360\/70R24; 420\/65R24<\/td><td class=\"column-4\">3500<\/td><td class=\"column-5\">+130\/-140<\/td>\n<\/tr>\n<tr class=\"row-41\">\n\t<td class=\"column-1\">24\u201d<\/td><td class=\"column-2\">W12<\/td><td class=\"column-3\">13.6R24; 380\/70R24; 380\/85R24<\/td><td class=\"column-4\">4700<\/td><td class=\"column-5\">+143\/-153<\/td>\n<\/tr>\n<tr class=\"row-42\">\n\t<td class=\"column-1\">24\u201d<\/td><td class=\"column-2\">W13<\/td><td class=\"column-3\">14.9R24; 420\/70R24; 420\/65R24<\/td><td class=\"column-4\">4700<\/td><td class=\"column-5\">+155.5\/-165.5<\/td>\n<\/tr>\n<tr class=\"row-43\">\n\t<td class=\"column-1\">24\u201d<\/td><td class=\"column-2\">DW13<\/td><td class=\"column-3\">400\/80R24<\/td><td class=\"column-4\">4300<\/td><td class=\"column-5\">+128\/-140<\/td>\n<\/tr>\n<tr class=\"row-44\">\n\t<td class=\"column-1\">24\u201d<\/td><td class=\"column-2\">W14L<\/td><td class=\"column-3\">W14L<\/td><td class=\"column-4\">4700<\/td><td class=\"column-5\">+160\/-170<\/td>\n<\/tr>\n<tr class=\"row-45\">\n\t<td class=\"column-1\">24\u201d<\/td><td class=\"column-2\">W15L<\/td><td class=\"column-3\">16.9R24; 480\/65R24; 480\/70R24<\/td><td class=\"column-4\">4700<\/td><td class=\"column-5\">+172\/-182<\/td>\n<\/tr>\n<tr class=\"row-46\">\n\t<td class=\"column-1\">24\u201d<\/td><td class=\"column-2\">W16L<\/td><td class=\"column-3\">500\/85R24; 540\/65R24<\/td><td class=\"column-4\">4700<\/td><td class=\"column-5\">+184\/-194<\/td>\n<\/tr>\n<tr class=\"row-47\">\n\t<td class=\"column-1\">24\u201d<\/td><td class=\"column-2\">DW16L<\/td><td class=\"column-3\">500\/85R24; 540\/65R24<\/td><td class=\"column-4\">4900<\/td><td class=\"column-5\">+111\/-123<\/td>\n<\/tr>\n<tr class=\"row-48\">\n\t<td class=\"column-1\">24\u201d<\/td><td class=\"column-2\">DW18L<\/td><td class=\"column-3\">540\/65R28<\/td><td class=\"column-4\">4900<\/td><td class=\"column-5\">+111\/-123<\/td>\n<\/tr>\n<tr class=\"row-49\">\n\t<td class=\"column-1\">26\u201d<\/td><td class=\"column-2\">DW12L<\/td><td class=\"column-3\">13.6-26<\/td><td class=\"column-4\">4000<\/td><td class=\"column-5\">+112\/-124<\/td>\n<\/tr>\n<tr class=\"row-50\">\n\t<td class=\"column-1\">26\u201d<\/td><td class=\"column-2\">DW16L<\/td><td class=\"column-3\">18.4R26; 480\/80R26; 480\/80-26; <br \/>\n580\/70R26<\/td><td class=\"column-4\">4500<\/td><td class=\"column-5\">+107.5\/-119.5<\/td>\n<\/tr>\n<tr class=\"row-51\">\n\t<td class=\"column-1\">26\u201d<\/td><td class=\"column-2\">DW20B<\/td><td class=\"column-3\">620\/70R26; 620\/75R26; 23.1-26<\/td><td class=\"column-4\">6350<\/td><td class=\"column-5\">+164.5\/-176.5<\/td>\n<\/tr>\n<tr class=\"row-52\">\n\t<td class=\"column-1\">26\u201d<\/td><td class=\"column-2\">DW25B<\/td><td class=\"column-3\">710\/65R26; 750\/65R26<\/td><td class=\"column-4\">6350<\/td><td class=\"column-5\">+228\/-240<\/td>\n<\/tr>\n<tr class=\"row-53\">\n\t<td class=\"column-1\">28\u201d<\/td><td class=\"column-2\">W7<\/td><td class=\"column-3\">225\/60R28<\/td><td class=\"column-4\">3700<\/td><td class=\"column-5\">+90\/-102<\/td>\n<\/tr>\n<tr class=\"row-54\">\n\t<td class=\"column-1\">28\u201d<\/td><td class=\"column-2\">W8<\/td><td class=\"column-3\">250\/85R28; 9.5-28<\/td><td class=\"column-4\">4200<\/td><td class=\"column-5\">+102.5\/-114.5<\/td>\n<\/tr>\n<tr class=\"row-55\">\n\t<td class=\"column-1\">28\u201d<\/td><td class=\"column-2\">W10<\/td><td class=\"column-3\">280\/85R28; 11.2R28; 320\/85R28; <br \/>\n12.4R28<\/td><td class=\"column-4\">4200<\/td><td class=\"column-5\">+122\/-134<\/td>\n<\/tr>\n<tr class=\"row-56\">\n\t<td class=\"column-1\">28\u201d<\/td><td class=\"column-2\">W11<\/td><td class=\"column-3\">320\/85R28; 360\/70R28; 420\/65R28<\/td><td class=\"column-4\">4200<\/td><td class=\"column-5\">+134\/ -146<\/td>\n<\/tr>\n<tr class=\"row-57\">\n\t<td class=\"column-1\">28\u201d<\/td><td class=\"column-2\">W12<\/td><td class=\"column-3\">13.6R28; 380\/70R28; 380\/85R28<\/td><td class=\"column-4\">4700<\/td><td class=\"column-5\">+146\/-158<\/td>\n<\/tr>\n<tr class=\"row-58\">\n\t<td class=\"column-1\">28\u201d<\/td><td class=\"column-2\">W13<\/td><td class=\"column-3\">14.9R28; 420\/70R28; 400\/80R28; <br \/>\n440\/80R28<\/td><td class=\"column-4\">4200<\/td><td class=\"column-5\">4200<\/td>\n<\/tr>\n<tr class=\"row-59\">\n\t<td class=\"column-1\">28\u201d<\/td><td class=\"column-2\">W14<\/td><td class=\"column-3\">440\/80R28; 440\/65R28<\/td><td class=\"column-4\">4700<\/td><td class=\"column-5\">+162\/-174<\/td>\n<\/tr>\n<tr class=\"row-60\">\n\t<td class=\"column-1\">28\u201d<\/td><td class=\"column-2\">W14L<\/td><td class=\"column-3\">440\/80R28; 440\/65R28<\/td><td class=\"column-4\">4700<\/td><td class=\"column-5\">+162\/-174<\/td>\n<\/tr>\n<tr class=\"row-61\">\n\t<td class=\"column-1\">28\u201d<\/td><td class=\"column-2\">W15L<\/td><td class=\"column-3\">16.9R28; 480\/70R28; 480\/65R28; <br \/>\n480\/70R28; 420\/85R28<\/td><td class=\"column-4\">5600<\/td><td class=\"column-5\">+175\/-187<\/td>\n<\/tr>\n<tr class=\"row-62\">\n\t<td class=\"column-1\">28\u201d<\/td><td class=\"column-2\">W16L<\/td><td class=\"column-3\">540\/65R28<\/td><td class=\"column-4\">4700<\/td><td class=\"column-5\">+187.5\/-199.5<\/td>\n<\/tr>\n<tr class=\"row-63\">\n\t<td class=\"column-1\">28\u201d<\/td><td class=\"column-2\">W18L<\/td><td class=\"column-3\">600\/60R28<\/td><td class=\"column-4\">5400<\/td><td class=\"column-5\">+212.5\/-224.5<\/td>\n<\/tr>\n<tr class=\"row-64\">\n\t<td class=\"column-1\">30\u201d<\/td><td class=\"column-2\">DW12<\/td><td class=\"column-3\">380\/85R30<\/td><td class=\"column-4\">4500<\/td><td class=\"column-5\">+118\/-130<\/td>\n<\/tr>\n<tr class=\"row-65\">\n\t<td class=\"column-1\">30\u201d<\/td><td class=\"column-2\">DW13<\/td><td class=\"column-3\">14.9R30<\/td><td class=\"column-4\">4200<\/td><td class=\"column-5\">+130.5\/-142.5<\/td>\n<\/tr>\n<tr class=\"row-66\">\n\t<td class=\"column-1\">30\u201d<\/td><td class=\"column-2\">DW14L<\/td><td class=\"column-3\">420\/90R30<\/td><td class=\"column-4\">4700<\/td><td class=\"column-5\">+115.5\/-127.5<\/td>\n<\/tr>\n<tr class=\"row-67\">\n\t<td class=\"column-1\">30\u201d<\/td><td class=\"column-2\">DW15L<\/td><td class=\"column-3\">16.9R30; 480\/70R30<\/td><td class=\"column-4\">5500<\/td><td class=\"column-5\">+128\/-140<\/td>\n<\/tr>\n<tr class=\"row-68\">\n\t<td class=\"column-1\">30\u201d<\/td><td class=\"column-2\">DW16L<\/td><td class=\"column-3\">18.4R30; 540\/65R30<\/td><td class=\"column-4\">4700<\/td><td class=\"column-5\">+140.5\/-152.5<\/td>\n<\/tr>\n<tr class=\"row-69\">\n\t<td class=\"column-1\">30\u201d<\/td><td class=\"column-2\">DW20B<\/td><td class=\"column-3\">23.1-30; 620\/75R30<\/td><td class=\"column-4\">5600<\/td><td class=\"column-5\">+172\/-184<\/td>\n<\/tr>\n<tr class=\"row-70\">\n\t<td class=\"column-1\">30\u201d<\/td><td class=\"column-2\">DW23B<\/td><td class=\"column-3\">710\/55R30<\/td><td class=\"column-4\">5600<\/td><td class=\"column-5\">+203\/-215\u00b2\u207e<\/td>\n<\/tr>\n<tr class=\"row-71\">\n\t<td class=\"column-1\">32\u201d<\/td><td class=\"column-2\">W7<\/td><td class=\"column-3\">210\/95R32; 8.3R32<\/td><td class=\"column-4\">2700<\/td><td class=\"column-5\">+115\/-127<\/td>\n<\/tr>\n<tr class=\"row-72\">\n\t<td class=\"column-1\">32\u201d<\/td><td class=\"column-2\">W8<\/td><td class=\"column-3\">230\/95R32; 9.5R32; 270\/80R32; <br \/>\n270\/95R32; 11.2R32<\/td><td class=\"column-4\">2700<\/td><td class=\"column-5\">+127\/-139<\/td>\n<\/tr>\n<tr class=\"row-73\">\n\t<td class=\"column-1\">32\u201d<\/td><td class=\"column-2\">W10<\/td><td class=\"column-3\">12.4R32; 320\/85R32<\/td><td class=\"column-4\">2700<\/td><td class=\"column-5\">+147\/-159<\/td>\n<\/tr>\n<tr class=\"row-74\">\n\t<td class=\"column-1\">32\u201d<\/td><td class=\"column-2\">W11<\/td><td class=\"column-3\">320\/85R82<\/td><td class=\"column-4\">2700<\/td><td class=\"column-5\">+159\/-171<\/td>\n<\/tr>\n<tr class=\"row-75\">\n\t<td class=\"column-1\">34\u201d<\/td><td class=\"column-2\">W10<\/td><td class=\"column-3\">320\/85R34<\/td><td class=\"column-4\">4000<\/td><td class=\"column-5\">+138\/-150<\/td>\n<\/tr>\n<tr class=\"row-76\">\n\t<td class=\"column-1\">34\u201d<\/td><td class=\"column-2\">W12<\/td><td class=\"column-3\">14.9R34<\/td><td class=\"column-4\">4000<\/td><td class=\"column-5\">+163\/-175<\/td>\n<\/tr>\n<tr class=\"row-77\">\n\t<td class=\"column-1\">34\u201d<\/td><td class=\"column-2\">W13<\/td><td class=\"column-3\">380\/85R34<\/td><td class=\"column-4\">4000<\/td><td class=\"column-5\">+175\/-187<\/td>\n<\/tr>\n<tr class=\"row-78\">\n\t<td class=\"column-1\">34\u201d<\/td><td class=\"column-2\">DW14L<\/td><td class=\"column-3\">420\/90R34<\/td><td class=\"column-4\">4500<\/td><td class=\"column-5\">+138\/-150<\/td>\n<\/tr>\n<tr class=\"row-79\">\n\t<td class=\"column-1\">34\u201d<\/td><td class=\"column-2\">W15L<\/td><td class=\"column-3\">420\/85R34; 480\/70R34<\/td><td class=\"column-4\">4500<\/td><td class=\"column-5\">+193\/-205<\/td>\n<\/tr>\n<tr class=\"row-80\">\n\t<td class=\"column-1\">34\u201d<\/td><td class=\"column-2\">DW15L<\/td><td class=\"column-3\">420\/85R34; 480\/70R34<\/td><td class=\"column-4\">4500<\/td><td class=\"column-5\">+150\/-162<\/td>\n<\/tr>\n<tr class=\"row-81\">\n\t<td class=\"column-1\">34\u201d<\/td><td class=\"column-2\">DW16L<\/td><td class=\"column-3\">18.4R34; 520\/70R34; 540\/65R34<\/td><td class=\"column-4\">5000<\/td><td class=\"column-5\">+162\/-174<\/td>\n<\/tr>\n<tr class=\"row-82\">\n\t<td class=\"column-1\">34\u201d<\/td><td class=\"column-2\">W16L<\/td><td class=\"column-3\">540\/65R34; 18.4R34<\/td><td class=\"column-4\">4500<\/td><td class=\"column-5\">+205\/-217<\/td>\n<\/tr>\n<tr class=\"row-83\">\n\t<td class=\"column-1\">34\u201d<\/td><td class=\"column-2\">DW18L<\/td><td class=\"column-3\">600\/65R34<\/td><td class=\"column-4\">5000<\/td><td class=\"column-5\">+190\/-202<\/td>\n<\/tr>\n<tr class=\"row-84\">\n\t<td class=\"column-1\">34\u201d<\/td><td class=\"column-2\">DW20B<\/td><td class=\"column-3\">600\/65R34; 600\/70R34<\/td><td class=\"column-4\">5600<\/td><td class=\"column-5\">+190\/-202\u00b2\u207e<\/td>\n<\/tr>\n<tr class=\"row-85\">\n\t<td class=\"column-1\">34\u201d<\/td><td class=\"column-2\">DW23B<\/td><td class=\"column-3\">600\/65R34; 600\/70R34<\/td><td class=\"column-4\">5600<\/td><td class=\"column-5\">+228\/-240\u00b2\u207e<\/td>\n<\/tr>\n<tr class=\"row-86\">\n\t<td class=\"column-1\">36\u201d<\/td><td class=\"column-2\">W7<\/td><td class=\"column-3\">8.3-36<\/td><td class=\"column-4\">2700<\/td><td class=\"column-5\">+113\/-125<\/td>\n<\/tr>\n<tr class=\"row-87\">\n\t<td class=\"column-1\">36\u201d<\/td><td class=\"column-2\">W8<\/td><td class=\"column-3\">270\/95R36; 11.2R36; 270\/80R36; <br \/>\n230\/95R36; 9.5R36<\/td><td class=\"column-4\">2700<\/td><td class=\"column-5\">+125\/-137<\/td>\n<\/tr>\n<tr class=\"row-88\">\n\t<td class=\"column-1\">36\u201d<\/td><td class=\"column-2\">W10<\/td><td class=\"column-3\">11.2R36; 12.4R36<\/td><td class=\"column-4\">2700<\/td><td class=\"column-5\">+145\/-157<\/td>\n<\/tr>\n<tr class=\"row-89\">\n\t<td class=\"column-1\">36\u201d<\/td><td class=\"column-2\">W11<\/td><td class=\"column-3\">12.4R36<\/td><td class=\"column-4\">2700<\/td><td class=\"column-5\">2700<\/td>\n<\/tr>\n<tr class=\"row-90\">\n\t<td class=\"column-1\">36\u201d<\/td><td class=\"column-2\">W12<\/td><td class=\"column-3\">W12<\/td><td class=\"column-4\">2700<\/td><td class=\"column-5\">+169\/-181<\/td>\n<\/tr>\n<tr class=\"row-91\">\n\t<td class=\"column-1\">38\u201d<\/td><td class=\"column-2\">W8<\/td><td class=\"column-3\">270\/95R38; 11.2R38<\/td><td class=\"column-4\">2500<\/td><td class=\"column-5\">+90\/-102<\/td>\n<\/tr>\n<tr class=\"row-92\">\n\t<td class=\"column-1\">38\u201d<\/td><td class=\"column-2\">W10<\/td><td class=\"column-3\">320\/85R38; 12.4R38<\/td><td class=\"column-4\">2500<\/td><td class=\"column-5\">+111\/-123<\/td>\n<\/tr>\n<tr class=\"row-93\">\n\t<td class=\"column-1\">38\u201d<\/td><td class=\"column-2\">DW10<\/td><td class=\"column-3\">320\/85R38; 12.4R38<\/td><td class=\"column-4\">3600<\/td><td class=\"column-5\">+118\/-130<\/td>\n<\/tr>\n<tr class=\"row-94\">\n\t<td class=\"column-1\">38\u201d<\/td><td class=\"column-2\">DW11<\/td><td class=\"column-3\">12.4R38<\/td><td class=\"column-4\">3600<\/td><td class=\"column-5\">+130\/-142<\/td>\n<\/tr>\n<tr class=\"row-95\">\n\t<td class=\"column-1\">38\u201d<\/td><td class=\"column-2\">W12<\/td><td class=\"column-3\">13.6R38; 380\/80R38<\/td><td class=\"column-4\">2500<\/td><td class=\"column-5\">+136\/-148<\/td>\n<\/tr>\n<tr class=\"row-96\">\n\t<td class=\"column-1\">38\u201d<\/td><td class=\"column-2\">DW12<\/td><td class=\"column-3\">13.6R38; 380\/80R38<\/td><td class=\"column-4\">3600<\/td><td class=\"column-5\">+142\/-154<\/td>\n<\/tr>\n<tr class=\"row-97\">\n\t<td class=\"column-1\">38\u201d<\/td><td class=\"column-2\">DW14L<\/td><td class=\"column-3\">420\/85R38; 480\/70R38<\/td><td class=\"column-4\">3600<\/td><td class=\"column-5\">+137\/-149<\/td>\n<\/tr>\n<tr class=\"row-98\">\n\t<td class=\"column-1\">38\u201d<\/td><td class=\"column-2\">DW15L<\/td><td class=\"column-3\">420\/85R38; 480\/70R38<\/td><td class=\"column-4\">4600<\/td><td class=\"column-5\">+149\/-163<\/td>\n<\/tr>\n<tr class=\"row-99\">\n\t<td class=\"column-1\">38\u201d<\/td><td class=\"column-2\">DW16L<\/td><td class=\"column-3\">18.4R38; 520\/70R38; 540\/65R38; <br \/>\n520\/85R38<\/td><td class=\"column-4\">4600<\/td><td class=\"column-5\">4600<\/td>\n<\/tr>\n<tr class=\"row-100\">\n\t<td class=\"column-1\">38\u201d<\/td><td class=\"column-2\">DW18L<\/td><td class=\"column-3\">20.8R38; 580\/70R38; 600\/65R38<\/td><td class=\"column-4\">9300<\/td><td class=\"column-5\">+186\/-200<\/td>\n<\/tr>\n<tr class=\"row-101\">\n\t<td class=\"column-1\">38\u201d<\/td><td class=\"column-2\">DW20B<\/td><td class=\"column-3\">600\/65R38; 650\/65R38; 620\/70R38; <br \/>\n650\/65R38<\/td><td class=\"column-4\">9000<\/td><td class=\"column-5\">+186\/-200\u00b2\u207e<\/td>\n<\/tr>\n<tr class=\"row-102\">\n\t<td class=\"column-1\">38\u201d<\/td><td class=\"column-2\">DW23B<\/td><td class=\"column-3\">650\/75R38; 650\/85R38; 710\/70R38<\/td><td class=\"column-4\">9500<\/td><td class=\"column-5\">+224\/-228\u00b2\u207e<\/td>\n<\/tr>\n<tr class=\"row-103\">\n\t<td class=\"column-1\">38\u201d<\/td><td class=\"column-2\">DW25B<\/td><td class=\"column-3\">710\/60R38<\/td><td class=\"column-4\">10000<\/td><td class=\"column-5\">+224\/-228<\/td>\n<\/tr>\n<tr class=\"row-104\">\n\t<td class=\"column-1\">38\u201d<\/td><td class=\"column-2\">DW27B<\/td><td class=\"column-3\">800\/70R38<\/td><td class=\"column-4\">11000<\/td><td class=\"column-5\">+230\/-235<\/td>\n<\/tr>\n<tr class=\"row-105\">\n\t<td class=\"column-1\">38\u201d<\/td><td class=\"column-2\">DW28B<\/td><td class=\"column-3\">850\/60R38<\/td><td class=\"column-4\">11500<\/td><td class=\"column-5\">+240\/-250<\/td>\n<\/tr>\n<tr class=\"row-106\">\n\t<td class=\"column-1\">42\u201d<\/td><td class=\"column-2\">W8<\/td><td class=\"column-3\">230\/95R42<\/td><td class=\"column-4\">2700<\/td><td class=\"column-5\">+125\/-141<\/td>\n<\/tr>\n<tr class=\"row-107\">\n\t<td class=\"column-1\">42\u201d<\/td><td class=\"column-2\">W10<\/td><td class=\"column-3\">320\/90R42<\/td><td class=\"column-4\">2700<\/td><td class=\"column-5\">+143\/-159<\/td>\n<\/tr>\n<tr class=\"row-108\">\n\t<td class=\"column-1\">42\u201d<\/td><td class=\"column-2\">DW16L<\/td><td class=\"column-3\">480\/80R42; 18.4R42<\/td><td class=\"column-4\">7000<\/td><td class=\"column-5\">+210\/-228<\/td>\n<\/tr>\n<tr class=\"row-109\">\n\t<td class=\"column-1\">42\u201d<\/td><td class=\"column-2\">DW18L<\/td><td class=\"column-3\">520\/85R42; 650\/65R42<\/td><td class=\"column-4\">8000<\/td><td class=\"column-5\">+235\/-253<\/td>\n<\/tr>\n<tr class=\"row-110\">\n\t<td class=\"column-1\">42\u201d<\/td><td class=\"column-2\">DW20B<\/td><td class=\"column-3\">620\/70R42<\/td><td class=\"column-4\">8000<\/td><td class=\"column-5\">+235\/-253\u00b2\u207e<\/td>\n<\/tr>\n<tr class=\"row-111\">\n\t<td class=\"column-1\">42\u201d<\/td><td class=\"column-2\">DW25B<\/td><td class=\"column-3\">710\/70R42; 710\/75R42<\/td><td class=\"column-4\">8000<\/td><td class=\"column-5\">+305\/-323<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-408 from cache --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c79499b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c79499b\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3fae1047\" data-id=\"3fae1047\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e7a6d89 elementor-widget elementor-widget-heading\" data-id=\"6e7a6d89\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Downloads<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-32e40ce5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"32e40ce5\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-2ce5aa79\" data-id=\"2ce5aa79\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70511290 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"70511290\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">TRACTOR FIXED WHEELS\u200b<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-20ac7782\" data-id=\"20ac7782\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fbef9f8 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1fbef9f8\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">IMPLEMENT WHEELS<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-2e3c980f\" data-id=\"2e3c980f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ab82271 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"3ab82271\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">WHEELS FOR COMBINE HARVESTERS<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-2547573a\" data-id=\"2547573a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1386a0c0 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1386a0c0\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">TRAILER AND FLOTATION WHEELS<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-b536ee\" data-id=\"b536ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1955076 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1955076\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">ROW CROP WHEELS<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9cf8426 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9cf8426\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-e9f28d8\" data-id=\"e9f28d8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24c94ea elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"24c94ea\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">ROW CROP WHEELS<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-df21282\" data-id=\"df21282\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bcbefdc elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"bcbefdc\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">WHEELS FOR FORESTRY MACHINES<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-01bde98\" data-id=\"01bde98\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97d6fc5 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"97d6fc5\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">CONSTRUCTION AND UTILTY WHEELS<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-d81e4c9\" data-id=\"d81e4c9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f30fc8 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0f30fc8\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">MINING WHEELS<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-09b3dfb\" data-id=\"09b3dfb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>TRACTOR FIXED WHEELS Contact Us TRACTOR FIXED WHEELS &#8220;Feel where traction goes hand in hand with comfort.&#8221; Extreme Durability \u2013 Discs up to 20mm thick for tough conditions. High Load Capacity \u2013 Steel rims up to 9mm thick for maximum strength. Precision &#038; Aesthetics \u2013 Advanced automation ensures perfect consistency. Superior Corrosion Protection \u2013 Multistage [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3256,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-11525","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.uniglorytire.com\/id\/wp-json\/wp\/v2\/pages\/11525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uniglorytire.com\/id\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.uniglorytire.com\/id\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.uniglorytire.com\/id\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uniglorytire.com\/id\/wp-json\/wp\/v2\/comments?post=11525"}],"version-history":[{"count":4,"href":"https:\/\/www.uniglorytire.com\/id\/wp-json\/wp\/v2\/pages\/11525\/revisions"}],"predecessor-version":[{"id":15630,"href":"https:\/\/www.uniglorytire.com\/id\/wp-json\/wp\/v2\/pages\/11525\/revisions\/15630"}],"up":[{"embeddable":true,"href":"https:\/\/www.uniglorytire.com\/id\/wp-json\/wp\/v2\/pages\/3256"}],"wp:attachment":[{"href":"https:\/\/www.uniglorytire.com\/id\/wp-json\/wp\/v2\/media?parent=11525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}