{"id":3960,"date":"2023-09-05T12:00:45","date_gmt":"2023-09-05T04:00:45","guid":{"rendered":"http:\/\/st.fogcm.com\/?page_id=3960"},"modified":"2025-09-29T10:54:16","modified_gmt":"2025-09-29T02:54:16","slug":"tracforce-306-r1","status":"publish","type":"page","link":"https:\/\/www.uniglorytire.com\/id\/bias-agriculture-tires\/tracforce\/tracforce-306-r1\/","title":{"rendered":"TRACFORCE-306"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3960\" class=\"elementor elementor-3960\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73c7043e elementor-section-height-min-height elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"73c7043e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_section_parallax_bg&quot;:&quot;yes&quot;,&quot;ekit_section_parallax_bg_speed&quot;:0.5,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59054f09\" data-id=\"59054f09\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-201d1b74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"201d1b74\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-50d84ab0\" data-id=\"50d84ab0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25a09f9a elementor-widget elementor-widget-elementskit-heading\" data-id=\"25a09f9a\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\">TRACTOR TIRE R-1<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b584ea1 elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-elementskit-button\" data-id=\"b584ea1\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"\/id\/contact\/\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tContact Us\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-572235d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"572235d1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-504e2224\" data-id=\"504e2224\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-679c4bf2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"679c4bf2\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e79d5f5\" data-id=\"e79d5f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-189227f4 elementor-widget elementor-widget-heading\" data-id=\"189227f4\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TRACFORCE 306<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-727a5cc1 elementor-widget elementor-widget-text-editor\" data-id=\"727a5cc1\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>&#8220;Feel where traction goes hand in hand with comfort.&#8221;<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77518bc0 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"77518bc0\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TRACFORCE 306 _Deep lugs are especially designed to provide high traction and long life under hard working conditions, including   on-the-road service.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Strong nylon carcass ensures full power  transmission, as well as good resistance.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-47a7edf9\" data-id=\"47a7edf9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a6f9c4d elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"6a6f9c4d\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Karusel Gambar\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 1\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6a6f9c4d\" data-elementor-lightbox-title=\"TRACFORCE-306-R1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjgyOSwidXJsIjoiaHR0cHM6XC9cL3d3dy51bmlnbG9yeXRpcmUuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wOFwvVFJBQ0ZPUkNFLTMwNi1SMS5qcGciLCJzbGlkZXNob3ciOiI2YTZmOWM0ZCJ9\" href=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/08\/TRACFORCE-306-R1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/08\/TRACFORCE-306-R1-300x300.jpg\" alt=\"TRACFORCE-306-R1\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-35d7fb5 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"35d7fb5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1689ae34\" data-id=\"1689ae34\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26c03bbf elementor-widget elementor-widget-elementskit-heading\" data-id=\"26c03bbf\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\">\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Tires are the essential point of contact between your car and the road. We work to ensure that your tires will always offer excellent braking, maximum safety, and pure driving pleasure.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3f81f630\" data-id=\"3f81f630\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24d785f6 elementor-align-right elementor-align--mobilecenter elementor-widget elementor-widget-elementskit-button\" data-id=\"24d785f6\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tKontak\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-748fa39 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"748fa39\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1af85d9a\" data-id=\"1af85d9a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48d062cc elementor-widget elementor-widget-heading\" data-id=\"48d062cc\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Technical detalis<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2b2d4b27 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b2d4b27\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5052ff2\" data-id=\"5052ff2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-323a3284 elementor-widget elementor-widget-image\" data-id=\"323a3284\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/knowlage-003-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-5039\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/knowlage-003-150x150.jpg 150w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/knowlage-003.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3892b6b5\" data-id=\"3892b6b5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59b9d6c3 elementor-widget elementor-widget-text-editor\" data-id=\"59b9d6c3\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>STUBBLE RESISTANT<\/strong><br \/>Uniglory R&amp;D teams invest more than ten years time and resources designing tires for excellent stubble resistance.<br \/>With the innovative solutions for stubble resistance, Uniglory Stubble Guardian Technology are specialized used in the tread area of all the Uniglory agriculture tires.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d013392 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3d013392\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">The unique carcass layer provides good toughness and rigidity, protect the tire crown effectively, solve the stubble problem under complex operation environment.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> The special rubber compounds enhances the fusion between the various raw materials, forms a sturdy protective layer.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">The reinforcement formula is perfect for resisting piercing forces from stubble.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> The optimized bead core design aims for the high torques of tractor tires and the rear axle tires of combine harvesters.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4740f51 elementor-widget elementor-widget-text-editor\" data-id=\"4740f51\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Results<br \/>The results are the outstanding service life of radial agriculture tire, increased by more than\u00a0<span style=\"color: #ffcc00;\"><strong>25%<\/strong><\/span>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-281e5881 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"281e5881\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a78e5d\" data-id=\"4a78e5d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8901982 elementor-widget elementor-widget-elementskit-tablepress\" data-id=\"8901982\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-tablepress.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elemenetskit-tablepress ekit-wid-con\" id=\"ekit_tablepress_8901982\">\n<table id=\"tablepress-240\" class=\"tablepress tablepress-id-240 tbody-has-connected-cells\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\"><span style=\"color:#FFFFFF;\"><strong>PATTERN NAME<\/strong><\/span><\/th><th class=\"column-2\"><span style=\"color:#FFFFFF;\"><strong>DESCRIPTION<\/strong><\/span><\/th><th class=\"column-3\"><span style=\"color:#FFFFFF;\"><strong>PR<\/strong><\/span><\/th><th class=\"column-4\"><span style=\"color:#FFFFFF;\"><strong>TT\/TL<\/strong><\/span><\/th><th class=\"column-5\"><span style=\"color:#FFFFFF;\"><strong>QTY\/40HQ<\/strong><\/span><\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>8\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">4.00-8<\/td><td class=\"column-3\">4PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">3800<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>10\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">4.00-10<\/td><td class=\"column-3\">4PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">3000<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>12\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">4.00-12<\/td><td class=\"column-3\">4PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">2800<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\">5.00-12<\/td><td class=\"column-3\">6PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">1500<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">6.00-12<\/td><td class=\"column-3\">6PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">1300<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">7.00-12<\/td><td class=\"column-3\">6PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">980<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>14\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">6.00-14<\/td><td class=\"column-3\">8PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">1200<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>15\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">5.00-15<\/td><td class=\"column-3\">6PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">1550<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">10.00-15<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">720<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>15.3\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">10.0\/75-15.3<\/td><td class=\"column-3\">12PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">600<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">10.0\/75-15.3<\/td><td class=\"column-3\">12PR<\/td><td class=\"column-4\">TL<\/td><td class=\"column-5\">600<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">11.5\/80-15.3<\/td><td class=\"column-3\">14PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">450<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">11.5\/80-15.3<\/td><td class=\"column-3\">14PR<\/td><td class=\"column-4\">TL<\/td><td class=\"column-5\">450<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>16\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">6.00-16<\/td><td class=\"column-3\">8PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">1005<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">6.50-16<\/td><td class=\"column-3\">8PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">840<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">7.50-16<\/td><td class=\"column-3\">8PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">720<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">9.50-16<\/td><td class=\"column-3\">6PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">380<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>17\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">5.50-17<\/td><td class=\"column-3\">6PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">1150<\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">15.0\/55-17<\/td><td class=\"column-3\">14PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">280<\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>20\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">7.50-20<\/td><td class=\"column-3\">8PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">540<\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">8.3-20<\/td><td class=\"column-3\">8PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">400<\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">8.5-20<\/td><td class=\"column-3\">8PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">400<\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">9.5-20<\/td><td class=\"column-3\">8PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">350<\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">11.2-20<\/td><td class=\"column-3\">8PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">300<\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">13.6-20<\/td><td class=\"column-3\">8PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">220<\/td>\n<\/tr>\n<tr class=\"row-36\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">16\/70-20<\/td><td class=\"column-3\">14PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">189<\/td>\n<\/tr>\n<tr class=\"row-37\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">16\/70-20<\/td><td class=\"column-3\">14PR<\/td><td class=\"column-4\">TL<\/td><td class=\"column-5\">189<\/td>\n<\/tr>\n<tr class=\"row-38\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">405\/70-20<\/td><td class=\"column-3\">14PR<\/td><td class=\"column-4\">TL<\/td><td class=\"column-5\">175<\/td>\n<\/tr>\n<tr class=\"row-39\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>22\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-40\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">8.3-22<\/td><td class=\"column-3\">6PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">380<\/td>\n<\/tr>\n<tr class=\"row-41\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>24\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-42\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">8.3-24<\/td><td class=\"column-3\">8PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">360<\/td>\n<\/tr>\n<tr class=\"row-43\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">9.5-24<\/td><td class=\"column-3\">8PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">280<\/td>\n<\/tr>\n<tr class=\"row-44\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">15-24<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">145<\/td>\n<\/tr>\n<tr class=\"row-45\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">11.2-24<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">240<\/td>\n<\/tr>\n<tr class=\"row-46\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">12.4-24<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">200<\/td>\n<\/tr>\n<tr class=\"row-47\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">13.6-24<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">190<\/td>\n<\/tr>\n<tr class=\"row-48\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">14.9-24<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">160<\/td>\n<\/tr>\n<tr class=\"row-49\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">16.9-24<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">110<\/td>\n<\/tr>\n<tr class=\"row-50\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>26\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-51\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">14.9-26<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">140<\/td>\n<\/tr>\n<tr class=\"row-52\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">18.4-26<\/td><td class=\"column-3\">12PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">85<\/td>\n<\/tr>\n<tr class=\"row-53\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">23.1-26<\/td><td class=\"column-3\">12PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">46<\/td>\n<\/tr>\n<tr class=\"row-54\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>28\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-55\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">9.5-28<\/td><td class=\"column-3\">8PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">270<\/td>\n<\/tr>\n<tr class=\"row-56\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">11.2-28<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">185<\/td>\n<\/tr>\n<tr class=\"row-57\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">12.4-28<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">170<\/td>\n<\/tr>\n<tr class=\"row-58\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">13.6-28<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">140<\/td>\n<\/tr>\n<tr class=\"row-59\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">14.9-28<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">125<\/td>\n<\/tr>\n<tr class=\"row-60\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">16.9-28<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">96<\/td>\n<\/tr>\n<tr class=\"row-61\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>30\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-62\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">14.9-30<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">112<\/td>\n<\/tr>\n<tr class=\"row-63\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">16.9-30<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">88<\/td>\n<\/tr>\n<tr class=\"row-64\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">18.4-30<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">78<\/td>\n<\/tr>\n<tr class=\"row-65\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">23.1-30<\/td><td class=\"column-3\">12PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">46<\/td>\n<\/tr>\n<tr class=\"row-66\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>32\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-67\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">9.5-32<\/td><td class=\"column-3\">8PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">190<\/td>\n<\/tr>\n<tr class=\"row-68\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">11-32<\/td><td class=\"column-3\">8PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">156<\/td>\n<\/tr>\n<tr class=\"row-69\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">24.5-32<\/td><td class=\"column-3\">16PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">44<\/td>\n<\/tr>\n<tr class=\"row-70\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">30.5L-32<\/td><td class=\"column-3\">18PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">28<\/td>\n<\/tr>\n<tr class=\"row-71\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>34\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-72\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">16.9-34<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">70<\/td>\n<\/tr>\n<tr class=\"row-73\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">18.4-34<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">60<\/td>\n<\/tr>\n<tr class=\"row-74\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>36\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-75\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">12.4-36<\/td><td class=\"column-3\">12PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">120<\/td>\n<\/tr>\n<tr class=\"row-76\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>38\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-77\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">11.2-38<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">125<\/td>\n<\/tr>\n<tr class=\"row-78\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">12-38<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">100<\/td>\n<\/tr>\n<tr class=\"row-79\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">13.6-38<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">95<\/td>\n<\/tr>\n<tr class=\"row-80\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">15.5-38<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">88<\/td>\n<\/tr>\n<tr class=\"row-81\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">16.9-38<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">64<\/td>\n<\/tr>\n<tr class=\"row-82\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">18.4-38<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">51<\/td>\n<\/tr>\n<tr class=\"row-83\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">20.8-38<\/td><td class=\"column-3\">12PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">40<\/td>\n<\/tr>\n<tr class=\"row-84\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">13.6\/12-38<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">98<\/td>\n<\/tr>\n<tr class=\"row-85\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>42\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-86\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">18.4-42<\/td><td class=\"column-3\">10PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">44<\/td>\n<\/tr>\n<tr class=\"row-87\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">20.8-42<\/td><td class=\"column-3\">12PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">36<\/td>\n<\/tr>\n<tr class=\"row-88\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>48\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-89\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">12.4-48<\/td><td class=\"column-3\">16PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">70<\/td>\n<\/tr>\n<tr class=\"row-90\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">14.9-48<\/td><td class=\"column-3\">16PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">56<\/td>\n<\/tr>\n<tr class=\"row-91\">\n\t<td colspan=\"5\" class=\"column-1\"><strong>54\"<\/strong><\/td>\n<\/tr>\n<tr class=\"row-92\">\n\t<td class=\"column-1\">TracForce 306<\/td><td class=\"column-2\">12.4-54<\/td><td class=\"column-3\">16PR<\/td><td class=\"column-4\">TT<\/td><td class=\"column-5\">60<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-240 from cache --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d47bbba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d47bbba\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1538c881\" data-id=\"1538c881\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c12d6ee elementor-widget elementor-widget-heading\" data-id=\"4c12d6ee\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Downloads<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6db3ada5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6db3ada5\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-66f2f02f\" data-id=\"66f2f02f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e267b28 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"5e267b28\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">TRACFORCE 206<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-20320298\" data-id=\"20320298\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5913989 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"5913989\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">TRACFORCE 202<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-2d1f9f41\" data-id=\"2d1f9f41\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ab69ac0 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"5ab69ac0\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">TRACFORCE 306<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-cb489c1\" data-id=\"cb489c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a705f0d elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2a705f0d\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">TRACFORCE 309<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-41be5662\" data-id=\"41be5662\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65d4a961 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"65d4a961\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE2OTkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" tabindex=\"-1\"><img decoding=\"async\" width=\"178\" height=\"178\" src=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png\" class=\"attachment-full size-full wp-image-5145\" alt=\"\" srcset=\"https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1.png 178w, https:\/\/www.uniglorytire.com\/wp-content\/uploads\/2023\/10\/\u4e0b\u8f7d-1-150x150.png 150w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">TRACFORCE 407<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>TRACTOR TIRE R-1 Contact Us TRACFORCE 306 &#8220;Feel where traction goes hand in hand with comfort.&#8221; TRACFORCE 306 _Deep lugs are especially designed to provide high traction and long life under hard working conditions, including on-the-road service. Strong nylon carcass ensures full power transmission, as well as good resistance. Tires are the essential point of [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3949,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-3960","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.uniglorytire.com\/id\/wp-json\/wp\/v2\/pages\/3960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uniglorytire.com\/id\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.uniglorytire.com\/id\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.uniglorytire.com\/id\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uniglorytire.com\/id\/wp-json\/wp\/v2\/comments?post=3960"}],"version-history":[{"count":4,"href":"https:\/\/www.uniglorytire.com\/id\/wp-json\/wp\/v2\/pages\/3960\/revisions"}],"predecessor-version":[{"id":15024,"href":"https:\/\/www.uniglorytire.com\/id\/wp-json\/wp\/v2\/pages\/3960\/revisions\/15024"}],"up":[{"embeddable":true,"href":"https:\/\/www.uniglorytire.com\/id\/wp-json\/wp\/v2\/pages\/3949"}],"wp:attachment":[{"href":"https:\/\/www.uniglorytire.com\/id\/wp-json\/wp\/v2\/media?parent=3960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}